{"id":50,"date":"2016-01-12T17:26:06","date_gmt":"2016-01-12T17:26:06","guid":{"rendered":"http:\/\/flatsome.dev\/?page_id=3569"},"modified":"2025-05-28T06:05:29","modified_gmt":"2025-05-28T06:05:29","slug":"image-box","status":"publish","type":"page","link":"https:\/\/www.tilend.com\/tilestore\/elements\/image-box\/","title":{"rendered":"Image Box"},"content":{"rendered":"\n  <div class=\"banner has-hover\" id=\"banner-13666153\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"650\" src=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-2.jpg\" class=\"bg attachment-large size-large\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-444076983\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"uppercase\"><strong>IMAGE BOX ELEMENT<\/strong><\/h3>\n<p class=\"lead\">Create amazing image boxes with unlimited style options.<\/p>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-444076983 {\n  width: 60%;\n}\n#text-box-444076983 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-13666153 {\n  padding-top: 500px;\n}\n#banner-13666153 .overlay {\n  background-color: rgba(0, 0, 0, 0.42);\n}\n<\/style>\n  <\/div>\n\n\n\n\t<section class=\"section\" id=\"section_233384042\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-323348098\">\n\n\t<div id=\"col-853957211\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg 400w, https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4>Simple Style<\/h4>\n<p>Some smaller text<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-188227099\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-bounce box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg 400w, https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4>Bounce\u00a0Style<\/h4>\n<p>Add anything here<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1696122339\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-badge hover-dark box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg 400w, https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4>Badge\u00a0Style<\/h4>\n<p>You can add shortcodes here<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1924225087\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-overlay dark box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg 400w, https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:1\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h2>Overlay Style<\/h2>\n<p class=\"lead\">Add any\u00a0elements here..<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-435763465\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-label box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg 400w, https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4>Label\u00a0Style<\/h4>\n<p>Add any\u00a0elements here..<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-748928710\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-shade dark box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg 400w, https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t<div class=\"shade\"><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4>Shade Style<\/h4>\n<p class=\"lead\">Add any\u00a0elements here..<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-992244231\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-push box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:90%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg 400w, https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text show-on-hover hover-bounce text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h2>Push Style<\/h2>\n<p>Add any\u00a0elements here..<\/p>\n<div class=\"is-divider divider clearfix\" ><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1916508976\" class=\"col medium-8 large-8\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-2 box-shadow-5-hover\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-vertical box-text-bottom\" >\n\n\t\t<div class=\"box-image\" style=\"width:48%;\">\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg 400w, https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h2>Vertical Style Boxed<\/h2>\n<p class=\"lead\">Add any\u00a0elements here..<\/p>\n<a class=\"button secondary is-outline\" style=\"border-radius:10px;\">\n\t\t<span>A button<\/span>\n\t<\/a>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_233384042 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_154097855\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1926643355\">\n\n\t<div id=\"col-1036717468\" class=\"col large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<h2>Create any kind of Image box by using the options in the Page Builder.<\/h2>\n<p class=\"lead\">We have created many examples here. Mix and Match effects to create your perfect Image Box<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-549613432\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner box-shadow-1\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg 400w, https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4>Simple Centered Style<\/h4>\n<p>Some smaller text<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-764001690\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-shadow-1 box-bounce box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg 400w, https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center dark\" style=\"background-color:rgb(66, 66, 66);\">\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4>Bounce\u00a0Style<\/h4>\n<p>Add anything here<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-41995223\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-overlay dark box-text-middle\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-blur image-cover\" style=\"padding-top:125%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg 400w, https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:1\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text show-on-hover hover-zoom-in text-center is-small\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h2>Overlay Style With Blur and Zoom<\/h2>\n<p>Add any\u00a0elements here..<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1312726271\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-overlay dark box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg 400w, https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t<div class=\"overlay\" style=\"background-color:1\"><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4>Circle with Blur In Effect<\/h4>\n<p>Add any\u00a0elements here..<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1531529992\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-shade dark box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:116%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg 400w, https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t<div class=\"shade\"><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h4>Simple Shade \u00a0Style<\/h4>\n<p class=\"lead\">A beautiful box.<\/p>\n<a class=\"button white is-white\" >\n\t\t<span>Quick View<\/span>\n\t<\/a>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-253772182\" class=\"col medium-4 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-shade dark box-text-middle\" >\n\n\t\t<div class=\"box-image\" style=\"border-radius:100%;\">\n\t\t\t\t\t\t<div class=\"image-zoom image-cover\" style=\"padding-top:100%;\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"260\" src=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1.jpg 400w, https:\/\/www.tilend.com\/tilestore\/wp-content\/uploads\/sites\/7\/2016\/08\/dummy-1-300x195.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t<div class=\"shade\"><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text show-on-hover hover-bounce text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n<h3 class=\"uppercase\">Circle Image<\/h3>\n<p class=\"lead\">Create this by adding radius 100% to the image.<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_154097855 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":5,"parent":90,"menu_order":15,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-50","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.tilend.com\/tilestore\/wp-json\/wp\/v2\/pages\/50","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tilend.com\/tilestore\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tilend.com\/tilestore\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tilend.com\/tilestore\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tilend.com\/tilestore\/wp-json\/wp\/v2\/comments?post=50"}],"version-history":[{"count":0,"href":"https:\/\/www.tilend.com\/tilestore\/wp-json\/wp\/v2\/pages\/50\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.tilend.com\/tilestore\/wp-json\/wp\/v2\/pages\/90"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tilend.com\/tilestore\/wp-json\/wp\/v2\/media\/5"}],"wp:attachment":[{"href":"https:\/\/www.tilend.com\/tilestore\/wp-json\/wp\/v2\/media?parent=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}